{"id":158,"count":1,"description":"","link":"https:\/\/thekitepower.com\/nl\/tag\/kite-airfoils\/","name":"Kite airfoils","slug":"kite-airfoils","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kite airfoils Archives - Kitepower<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/thekitepower.com\/nl\/tag\/kite-airfoils\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kite airfoils Archives - Kitepower\" \/>\n<meta property=\"og:url\" content=\"https:\/\/thekitepower.com\/nl\/tag\/kite-airfoils\/\" \/>\n<meta property=\"og:site_name\" content=\"Kitepower\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/thekitepower.com\\\/tag\\\/kite-airfoils\\\/\",\"url\":\"https:\\\/\\\/thekitepower.com\\\/tag\\\/kite-airfoils\\\/\",\"name\":\"Kite airfoils Archives - Kitepower\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/thekitepower.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/thekitepower.com\\\/tag\\\/kite-airfoils\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/thekitepower.com\\\/tag\\\/kite-airfoils\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/thekitepower.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kite airfoils\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/thekitepower.com\\\/#website\",\"url\":\"https:\\\/\\\/thekitepower.com\\\/\",\"name\":\"Kitepower\",\"description\":\"Powering Business Beyond the Grid\",\"publisher\":{\"@id\":\"https:\\\/\\\/thekitepower.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/thekitepower.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/thekitepower.com\\\/#organization\",\"name\":\"Kitepower\",\"url\":\"https:\\\/\\\/thekitepower.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/thekitepower.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/thekitepower.com\\\/wp-content\\\/uploads\\\/Kitepower-Logo-Vertical-Blues-Margins.png\",\"contentUrl\":\"https:\\\/\\\/thekitepower.com\\\/wp-content\\\/uploads\\\/Kitepower-Logo-Vertical-Blues-Margins.png\",\"width\":657,\"height\":657,\"caption\":\"Kitepower\"},\"image\":{\"@id\":\"https:\\\/\\\/thekitepower.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/kitepower.bv\",\"https:\\\/\\\/www.instagram.com\\\/thekitepower\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kitepower-bv\\\/\",\"https:\\\/\\\/www.youtube.com\\\/@kitepower-airbornewindenergy\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kite airfoils Archives - Kitepower","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/thekitepower.com\/nl\/tag\/kite-airfoils\/","og_locale":"nl_NL","og_type":"article","og_title":"Kite airfoils Archives - Kitepower","og_url":"https:\/\/thekitepower.com\/nl\/tag\/kite-airfoils\/","og_site_name":"Kitepower","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/thekitepower.com\/tag\/kite-airfoils\/","url":"https:\/\/thekitepower.com\/tag\/kite-airfoils\/","name":"Kite airfoils Archives - Kitepower","isPartOf":{"@id":"https:\/\/thekitepower.com\/#website"},"breadcrumb":{"@id":"https:\/\/thekitepower.com\/tag\/kite-airfoils\/#breadcrumb"},"inLanguage":"nl-NL"},{"@type":"BreadcrumbList","@id":"https:\/\/thekitepower.com\/tag\/kite-airfoils\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/thekitepower.com\/"},{"@type":"ListItem","position":2,"name":"Kite airfoils"}]},{"@type":"WebSite","@id":"https:\/\/thekitepower.com\/#website","url":"https:\/\/thekitepower.com\/","name":"Kitepower","description":"Energie voor bedrijven, voorbij het net","publisher":{"@id":"https:\/\/thekitepower.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/thekitepower.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/thekitepower.com\/#organization","name":"Kitepower","url":"https:\/\/thekitepower.com\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/thekitepower.com\/#\/schema\/logo\/image\/","url":"https:\/\/thekitepower.com\/wp-content\/uploads\/Kitepower-Logo-Vertical-Blues-Margins.png","contentUrl":"https:\/\/thekitepower.com\/wp-content\/uploads\/Kitepower-Logo-Vertical-Blues-Margins.png","width":657,"height":657,"caption":"Kitepower"},"image":{"@id":"https:\/\/thekitepower.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/kitepower.bv","https:\/\/www.instagram.com\/thekitepower\/","https:\/\/www.linkedin.com\/company\/kitepower-bv\/","https:\/\/www.youtube.com\/@kitepower-airbornewindenergy"]}]}},"_links":{"self":[{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/tags\/158","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/posts?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/energy-source?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/faq?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/market?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/milestone?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/partner?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/project?tags=158"},{"href":"https:\/\/thekitepower.com\/nl\/wp-json\/wp\/v2\/publication?tags=158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}